{"id":3423,"date":"2025-12-30T18:56:34","date_gmt":"2025-12-30T15:56:34","guid":{"rendered":"https:\/\/157.viiieme.com\/?post_type=product&#038;p=3423"},"modified":"2025-12-30T19:00:40","modified_gmt":"2025-12-30T16:00:40","slug":"%d8%b1%d9%88%d9%84%d9%83%d8%b3-%d9%8a%d8%ae%d8%aa-%d9%85%d8%a7%d8%b3%d8%aa%d8%b1-%d9%83%d8%a7%d9%85-%d9%86%d8%b3%d8%ae%d8%a9","status":"publish","type":"product","link":"https:\/\/157.viiieme.com\/en\/product\/%d8%b1%d9%88%d9%84%d9%83%d8%b3-%d9%8a%d8%ae%d8%aa-%d9%85%d8%a7%d8%b3%d8%aa%d8%b1-%d9%83%d8%a7%d9%85-%d9%86%d8%b3%d8%ae%d8%a9\/","title":{"rendered":"(\u0646\u0633\u062e\u0629)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3428,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"product_brand":[189],"product_cat":[181,160],"product_tag":[],"product_condition":[],"partner_store":[],"class_list":["post-3423","product","type-product","status-publish","has-post-thumbnail","product_brand-189","product_cat-181","product_cat-160","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-after_add_to_cart"],"acf":[],"_links":{"self":[{"href":"https:\/\/157.viiieme.com\/en\/wp-json\/wp\/v2\/product\/3423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/157.viiieme.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/157.viiieme.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/157.viiieme.com\/en\/wp-json\/wp\/v2\/comments?post=3423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/157.viiieme.com\/en\/wp-json\/wp\/v2\/media\/3428"}],"wp:attachment":[{"href":"https:\/\/157.viiieme.com\/en\/wp-json\/wp\/v2\/media?parent=3423"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/157.viiieme.com\/en\/wp-json\/wp\/v2\/product_brand?post=3423"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/157.viiieme.com\/en\/wp-json\/wp\/v2\/product_cat?post=3423"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/157.viiieme.com\/en\/wp-json\/wp\/v2\/product_tag?post=3423"},{"taxonomy":"product_condition","embeddable":true,"href":"https:\/\/157.viiieme.com\/en\/wp-json\/wp\/v2\/product_condition?post=3423"},{"taxonomy":"partner_store","embeddable":true,"href":"https:\/\/157.viiieme.com\/en\/wp-json\/wp\/v2\/partner_store?post=3423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}